{"id":2383,"date":"2025-10-31T10:21:12","date_gmt":"2025-10-31T09:21:12","guid":{"rendered":"https:\/\/bilbilhouse.com\/?page_id=2383"},"modified":"2025-11-10T14:52:53","modified_gmt":"2025-11-10T13:52:53","slug":"alta-de-vecinos","status":"publish","type":"page","link":"https:\/\/bilbilhouse.com\/en\/alta-de-vecinos\/","title":{"rendered":"Registration of neighbours"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2383\" class=\"elementor elementor-2383\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b857747 e-flex e-con-boxed e-con e-parent\" data-id=\"b857747\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6ad37ed e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"6ad37ed\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72d2447 elementor-widget elementor-widget-metform\" data-id=\"72d2447\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_form_multistep_status&quot;:&quot;mf-multistep-container&quot;}\" data-widget_type=\"metform.default\">\n\t\t\t\t\t<div id=\"mf-response-props-id-2384\" data-previous-steps-style=\"\" data-editswitchopen=\"no\" data-response_type=\"alert\" data-erroricon=\"\" data-successicon=\"\" data-messageposition=\"\" class=\"  mf_slide_direction_horizontal mf-multistep-container mf-form-multistep-nav-yes mf-scroll-top-no\">\n\t\t<div class=\"formpicker_warper formpicker_warper_editable\" data-metform-formpicker-key=\"2384\" >\n\t\t\t\t\n\t\t\t<div class=\"mf-widget-container\">\n\t\t\t\t\r\n\t\t<div\r\n\t\t\tid=\"metform-wrap-72d2447-2384\"\r\n\t\t\tclass=\"mf-form-wrapper\"\r\n\t\t\tdata-form-id=\"2384\"\r\n\t\t\tdata-action=\"https:\/\/bilbilhouse.com\/en\/wp-json\/metform\/v1\/entries\/insert\/2384\"\r\n\t\t\tdata-wp-nonce=\"86d188ed31\"\r\n\t\t\tdata-form-nonce=\"24d722b928\"\r\n\t\t\tdata-quiz-summery = \"false\"\r\n\t\t\tdata-save-progress = \"false\"\r\n\t\t\tdata-form-type=\"general-form\"\r\n\t\t\tdata-stop-vertical-effect=\"\"\r\n\t\t\tdata-payment-submit-before=\"0\"\r\n\t\t\t><\/div>\r\n\r\n\r\n\t\t<!----------------------------- \r\n\t\t\t* controls_data : find the the props passed indie of data attribute\r\n\t\t\t* props.SubmitResponseMarkup : contains the markup of error or success message\r\n\t\t\t* https:\/\/developer.mozilla.org\/en-US\/docs\/Web\/JavaScript\/Reference\/Template_literals\r\n\t\t--------------------------- -->\r\n\r\n\t\t\t\t<script type=\"text\/mf\" class=\"mf-template\">\r\n\t\t\tfunction controls_data (value){\r\n\t\t\t\tlet currentWrapper = \"mf-response-props-id-2384\";\r\n\t\t\t\tlet currentEl = document.getElementById(currentWrapper);\r\n\t\t\t\t\r\n\t\t\t\treturn currentEl ? currentEl.dataset[value] : false\r\n\t\t\t}\r\n\r\n\r\n\t\t\tlet is_edit_mode = '' ? true : false;\r\n\t\t\tlet message_position = controls_data('messageposition') || 'top';\r\n\r\n\t\t\t\r\n\t\t\tlet message_successIcon = controls_data('successicon') || '';\r\n\t\t\tlet message_errorIcon = controls_data('erroricon') || '';\r\n\t\t\tlet message_editSwitch = controls_data('editswitchopen') === 'yes' ? true : false;\r\n\t\t\tlet message_proClass = controls_data('editswitchopen') === 'yes' ? 'mf_pro_activated' : '';\r\n\t\t\t\r\n\t\t\tlet is_dummy_markup = is_edit_mode && message_editSwitch ? true : false;\r\n\r\n\t\t\t\r\n\t\t\treturn html`\r\n\t\t\t\t<form\r\n\t\t\t\t\tclassName=\"metform-form-content\"\r\n\t\t\t\t\tref=${parent.formContainerRef}\r\n\t\t\t\t\tonSubmit=${ validation.handleSubmit( parent.handleFormSubmit ) }\r\n\t\t\t\t\r\n\t\t\t\t\t>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'top' ?  props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' :  message_position === 'top' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\r\n\t\t\t\t\t<!--------------------------------------------------------\r\n\t\t\t\t\t*** IMPORTANT \/ DANGEROUS ***\r\n\t\t\t\t\t${html``} must be used as in immediate child of \"metform-form-main-wrapper\"\r\n\t\t\t\t\tclass otherwise multistep form will not run at all\r\n\t\t\t\t\t---------------------------------------------------------->\r\n\r\n\t\t\t\t\t<div className=\"metform-form-main-wrapper\" key=${'hide-form-after-submit'} ref=${parent.formRef}>\r\n\t\t\t\t\t${html`\r\n\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" key=\"2\" data-elementor-id=\"2384\" className=\"elementor elementor-2384\" data-elementor-post-type=\"metform-form\">\n\t\t\t\t<div className=\"elementor-element elementor-element-6a7e585 e-flex e-con-boxed e-con e-parent\" data-id=\"6a7e585\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;metform_multistep_settings_title&quot;:&quot;Informaci\\u00f3n&quot;,&quot;metform_multistep_settings_icon&quot;:{&quot;value&quot;:&quot;fas fa-info-circle&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\">\n\t\t\t\t\t<div className=\"e-con-inner\">\n\t\t\t\t<div className=\"elementor-element elementor-element-73e75f0 elementor-widget elementor-widget-heading\" data-id=\"73e75f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 className=\"elementor-heading-title elementor-size-default\">Informaci\u00f3n para los vecinos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-0478266 elementor-widget elementor-widget-text-editor\" data-id=\"0478266\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Para retirar las <strong>nuevas tarjetas de socios<\/strong>, que dar\u00e1n acceso a las instalaciones deportivas y permitir\u00e1 a los vecinos disfrutar de precios especiales, ser\u00e1 necesario completar este formulario <strong>una sola vez por persona<\/strong>.\u00a0<\/p><ul><li>Ser\u00e1 obligatorio que el usuario disponga de tarjeta de socio para disfrutar de precios especiales.<\/li><li>Para acceder al gimnasio, ser\u00e1 obligatorio hacer uso del torno, o pasar por la oficina.\u00a0<\/li><li>La edad m\u00ednima para usar el gimnasio es de 16 a\u00f1os cumplidos.<\/li><li>Los menores deber\u00e1n venir acompa\u00f1ados en la primera inscripci\u00f3n por su padre\/madre o tutor legal, que firmar\u00e1 su consentimiento y presentar\u00e1 el DNI del menor.<\/li><li>Los hijos menores de edad no empadronados en la vivienda de su progenitor, sean propietarios o arrendatarios, podr\u00e1n obtener la tarjeta de socio.<\/li><li>Todo propietario que tenga su vivienda alquilada ceder\u00e1 su derecho de uso y disfrute a inquilinos de larga temporada y convivientes empadronados en la vivienda.<\/li><li>Para retirar la nueva tarjeta de acceso, con el fin de confirmar la relaci\u00f3n con la vivienda, se\u00a0 solicitar\u00e1:<ul><li style=${{ 'font-size': '16px', }}>nota simple o\u00a0<\/li><li><span style=${{ 'background-color': 'transparent', }}>el contrato de arrendamiento de larga temporada o<\/span><\/li><li><span style=${{ 'background-color': 'transparent', }}>el certificado de empadronamiento<\/span><\/li><\/ul><\/li><li>La primera tarjeta expedida a los vecinos tiene car\u00e1cter gratuito. En caso de p\u00e9rdida, la emisi\u00f3n de una nueva tarjeta tendr\u00e1 un coste de 10 \u20ac.<\/li><li>Para poder disfrutar de los precios especiales de socios en actividades de raqueta, \u00e9ste deber\u00e1 personarse en la oficina deportiva a la hora de realizar el pago. Ning\u00fan otro jugador podr\u00e1 pagar en su nombre.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div className=\"elementor-element elementor-element-d70a8cc e-con-full e-flex e-con e-child\" data-id=\"d70a8cc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div className=\"elementor-element elementor-element-1a31d47 elementor-widget__width-auto e-transform mf-btn--center elementor-widget elementor-widget-mf-next-step\" data-id=\"1a31d47\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-10,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"mf-next-step.default\">\n\t\t\t\t\t\t\t<div className=\"mf-btn-wraper \">\n\t\t\t\t\t\t\t<button type=\"button\"\n\t\t\t\t\t\tclassName=\"metform-btn metfrom-next-step \"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-direction=\"next\"\n\t\t\t\t\t\t\t\t\t\t\t\tonClick=${ parent.handleMultiStepBtns }\n\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t${ parent.decodeEntities(`Siguiente paso`) } \t\t\t\t\t<i aria-hidden=\"true\" className=\" ti-arrow-right\"><\/i>\t\t\t\t<\/button>\n\t\t\t        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div className=\"elementor-element elementor-element-0d9fbea e-con-full e-flex e-con e-parent\" data-id=\"0d9fbea\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;metform_multistep_settings_title&quot;:&quot;Vecino&quot;,&quot;metform_multistep_settings_icon&quot;:{&quot;value&quot;:&quot;fas fa-user-edit&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\">\n\t\t\t\t<div className=\"elementor-element elementor-element-db8779d elementor-widget elementor-widget-heading\" data-id=\"db8779d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 className=\"elementor-heading-title elementor-size-default\">Datos Personales<\/h2>\t\t\t\t<\/div>\n\t\t<div className=\"elementor-element elementor-element-4fe72da e-con-full e-grid e-con e-child\" data-id=\"4fe72da\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;metform_multistep_settings_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;}}\">\n\t\t\t\t<div className=\"elementor-element elementor-element-3b739d5 elementor-widget elementor-widget-mf-text\" data-id=\"3b739d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-nombre&quot;,&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-3b739d5\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Nombre`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input \"\r\n\t\t\t\tid=\"mf-input-text-3b739d5\"\r\n\t\t\t\tname=\"mf-nombre\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Nombre`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-nombre'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"Este campo es obligatorio\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-nombre\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-e90a4d3 elementor-widget elementor-widget-mf-text\" data-id=\"e90a4d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-apellidos&quot;,&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-e90a4d3\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Apellidos`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input \"\r\n\t\t\t\tid=\"mf-input-text-e90a4d3\"\r\n\t\t\t\tname=\"mf-apellidos\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Apellidos`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-apellidos'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"Este campo es obligatorio\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-apellidos\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-84e0aca elementor-widget elementor-widget-mf-text\" data-id=\"84e0aca\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-dni&quot;,&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-84e0aca\">\r\n\t\t\t\t\t${ parent.decodeEntities(`DNI`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input \"\r\n\t\t\t\tid=\"mf-input-text-84e0aca\"\r\n\t\t\t\tname=\"mf-dni\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`DNI`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-dni'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"Este campo es obligatorio\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-dni\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-5bb0bc6 elementor-widget elementor-widget-mf-date\" data-id=\"5bb0bc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-fecha-nacimiento&quot;,&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-date.default\">\n\t\t\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-date-5bb0bc6\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Fecha de Nacimiento`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<${props.Flatpickr}\r\n\t\t\t\t\tname=\"mf-fecha-nacimiento\"\r\n\t\t\t\t\tclassName=\"mf-input mf-date-input mf-left-parent  \"\r\n\t\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Fecha de nacimiento`) } \"\r\n\t\t\t\t\toptions=${{\"minDate\":\"\",\"maxDate\":\"\",\"dateFormat\":\"d-m-Y\",\"enableTime\":\"\",\"disable\":[\"01-01-1970\"],\"mode\":\"single\",\"static\":true,\"disableMobile\":true,\"time_24hr\":false}}\r\n\t\t\t\t\tvalue=${parent.getValue('mf-fecha-nacimiento')}\r\n\t\t\t\t\tonInput=${parent.handleDateTime}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-fecha-nacimiento'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el => props.DateWidget(\r\n\t\t\t\t\t\t\tel, \r\n\t\t\t\t\t\t\t'es', \r\n\t\t\t\t\t\t\t{\"message\":\"Este campo es obligatorio\",\"required\":true},  \r\n\t\t\t\t\t\t\tregister, \r\n\t\t\t\t\t\t\tparent \r\n\t\t\t\t\t\t)}\r\n\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-fecha-nacimiento\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-6925000 elementor-widget elementor-widget-mf-telephone\" data-id=\"6925000\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-telefonos&quot;,&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-telephone.default\">\n\t\t\t\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-telephone-6925000\">\n\t\t\t\t\t${ parent.decodeEntities(`Tel\u00e9fono(s)`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\n\t\t\t\t<\/label>\n\t\t\t\n\t\t\t<input\n\t\t\t\ttype=\"tel\"\n\t\t\t\tclassName=\"mf-input \"\n\t\t\t\tid=\"mf-input-telephone-6925000\" \n\t\t\t\tname=\"mf-telefonos\"\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Tel\u00e9fono`) } \"\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\n\t\t\t\t\taria-invalid=${validation.errors['mf-telefonos'] ? 'true' : 'false'}\n\t\t\t\t\tref=${el => parent.activateValidation({\"message\":\"Este campo es obligatorio\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\n\t\t\t\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"mf-telefonos\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-00df2fd elementor-widget elementor-widget-mf-email\" data-id=\"00df2fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-email&quot;,&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-email.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-email-00df2fd\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Correo electr\u00f3nico`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input \r\n\t\t\t\ttype=\"email\" \r\n\t\t\t\t \r\n\t\t\t\tdefaultValue=\"\" \r\n\t\t\t\tclassName=\"mf-input \" \r\n\t\t\t\tid=\"mf-input-email-00df2fd\" \r\n\t\t\t\tname=\"mf-email\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Email`) } \" \r\n\t\t\t\t \r\n\t\t\t\tonBlur=${parent.handleChange} onFocus=${parent.handleChange} aria-invalid=${validation.errors['mf-email'] ? 'true' : 'false' } \r\n\t\t\t\tref=${el=> parent.activateValidation({\"message\":\"Este campo es obligatorio\",\"emailMessage\":\"Please enter a valid Email address\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t<${validation.ErrorMessage} \r\n\t\t\t\terrors=${validation.errors} \r\n\t\t\t\tname=\"mf-email\" \r\n\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-b7ed97b elementor-widget elementor-widget-mf-select\" data-id=\"b7ed97b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-relacion&quot;,&quot;mf_input_list&quot;:[{&quot;mf_input_option_text&quot;:&quot;Propietario&quot;,&quot;mf_input_option_value&quot;:&quot;Propietario&quot;,&quot;_id&quot;:&quot;e9ef1d1&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Inquilino&quot;,&quot;mf_input_option_value&quot;:&quot;Inquilino&quot;,&quot;_id&quot;:&quot;4a70f12&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Conviviente&quot;,&quot;mf_input_option_value&quot;:&quot;Conviviente&quot;,&quot;_id&quot;:&quot;ce5804d&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;}],&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-select.default\">\n\t\t\t\t\t\n\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-select-b7ed97b\">\n\t\t\t\t\t${ parent.decodeEntities(`Relaci\u00f3n con la vivienda`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\n\t\t\t\t<\/label>\n            \n            <${props.Select}\n                className=${\"mf-input mf-input-select  \" + ( validation.errors['mf-relacion'] ? 'mf-invalid' : '' )}\n                classNamePrefix=\"mf_select\"\n                name=\"mf-relacion\"\n                placeholder=\"${ parent.decodeEntities(`Relaci\u00f3n`) } \"\n                isSearchable=${false}\n                options=${[{\"label\":\"Propietario\",\"value\":\"Propietario\",\"isDisabled\":false},{\"label\":\"Inquilino\",\"value\":\"Inquilino\",\"isDisabled\":false},{\"label\":\"Conviviente\",\"value\":\"Conviviente\",\"isDisabled\":false}]}\n                value=${parent.getValue(\"mf-relacion\") ? [{\"label\":\"Propietario\",\"value\":\"Propietario\",\"isDisabled\":false},{\"label\":\"Inquilino\",\"value\":\"Inquilino\",\"isDisabled\":false},{\"label\":\"Conviviente\",\"value\":\"Conviviente\",\"isDisabled\":false}].filter(item => item.value === parent.getValue(\"mf-relacion\"))[0] : []}\n                onChange=${(e)=> parent.handleSelect(e, \"mf-relacion\")}\n                ref=${() => {\n\t\t\t\t                    register({ name: \"mf-relacion\" }, parent.activateValidation({\"message\":\"Este campo es obligatorio\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true}));\n                    if ( parent.getValue(\"mf-relacion\") === '' && false ) {\n\t\t\t\t    parent.setValue( 'mf-relacion', '', true );\n                        parent.handleChange({\n                            target: {\n                                name: 'mf-relacion',\n                                value: ''\n                            }\n                        });\n                    }\n                }}\n                \/>\n\n            \t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"mf-relacion\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-873b952 elementor-widget elementor-widget-mf-text\" data-id=\"873b952\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-text&quot;,&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-873b952\">\r\n\t\t\t\t\t${ parent.decodeEntities(`N\u00baSocio, en caso de conocerlo`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\"><\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input \"\r\n\t\t\t\tid=\"mf-input-text-873b952\"\r\n\t\t\t\tname=\"mf-text\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`N\u00famero de socio`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-text'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":false,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-text\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div className=\"elementor-element elementor-element-09c6d12 e-con-full e-flex e-con e-child\" data-id=\"09c6d12\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;metform_multistep_settings_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;}}\">\n\t\t\t\t<div className=\"elementor-element elementor-element-f4fa24d elementor-widget elementor-widget-mf-gdpr-consent\" data-id=\"f4fa24d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-acepto-condiciones&quot;,&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-gdpr-consent.default\">\n\t\t\t\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\n\t\t\t<div className=\"mf-checkbox multi-option-input-type\" id=\"mf-input-gdpr-f4fa24d\">\n\t\t\t\t<div className=\"mf-checkbox-option\">\n\t\t\t\t\t<label>\n\t\t\t\t\t\t\t\t\t\t\t\t<input\n\t\t\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\t\t\tclassName=\"mf-input mf-checkbox-input \"\n\t\t\t\t\t\t\tname=\"mf-acepto-condiciones\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tonInput=${ parent.handleOptin }\n\t\t\t\t\t\t\t\taria-invalid=${validation.errors['mf-acepto-condiciones'] ? 'true' : 'false'}\n\t\t\t\t\t\t\t\tref=${ el => parent.activateValidation({\"message\":\"Este campo es obligatorio\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el) }\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\tConfirmo que: <ul><li>En caso de ser <b>el nuevo propietario<\/b> de esta vivienda, se pueden eliminar las personas asociadas a esta vivienda previamente.<\/li>\n<li>En caso de ser <b>el nuevo inquilino en esta vivienda<\/b>, se pueden eliminar las personas asignadas previamente a la misma.<\/li>\n<li>En caso de ser <b>conviviente en esta vivienda<\/b> no ser\u00e1 necesario eliminar a las personas previamente asignadas.<\/li>\n<\/ul>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"mf-acepto-condiciones\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div className=\"elementor-element elementor-element-925ebdd e-con-full e-flex e-con e-child\" data-id=\"925ebdd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div className=\"elementor-element elementor-element-64f5284 elementor-widget__width-auto e-transform mf-btn--center elementor-widget elementor-widget-mf-prev-step\" data-id=\"64f5284\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-10,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"mf-prev-step.default\">\n\t\t\t\t\t\t\t<div className=\"mf-btn-wraper \">\n\t\t\t\t\t\t\t<button type=\"button\"\n\t\t\t\t\t\tclassName=\"metform-btn metfrom-prev-step \"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-direction=\"prev\"\n\t\t\t\t\t\t\t\t\t\t\t\tonClick=${ parent.handleMultiStepBtns }\n\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t<i aria-hidden=\"true\" className=\" ti-arrow-left\"><\/i>\t\t\t\t\t${ parent.decodeEntities(`Paso previo`) } \t\t\t\t<\/button>\n\t\t\t\t        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-fe3ae2d elementor-widget__width-auto e-transform mf-btn--center elementor-widget elementor-widget-mf-next-step\" data-id=\"fe3ae2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-10,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"mf-next-step.default\">\n\t\t\t\t\t\t\t<div className=\"mf-btn-wraper \">\n\t\t\t\t\t\t\t<button type=\"button\"\n\t\t\t\t\t\tclassName=\"metform-btn metfrom-next-step \"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-direction=\"next\"\n\t\t\t\t\t\t\t\t\t\t\t\tonClick=${ parent.handleMultiStepBtns }\n\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t${ parent.decodeEntities(`Siguiente paso`) } \t\t\t\t\t<i aria-hidden=\"true\" className=\" ti-arrow-right\"><\/i>\t\t\t\t<\/button>\n\t\t\t        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div className=\"elementor-element elementor-element-4bbd7f7 e-con-full e-flex e-con e-parent\" data-id=\"4bbd7f7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;metform_multistep_settings_title&quot;:&quot;Vivienda&quot;,&quot;metform_multistep_settings_icon&quot;:{&quot;value&quot;:&quot;fas fa-house-user&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\">\n\t\t\t\t<div className=\"elementor-element elementor-element-ae7d2c7 elementor-widget elementor-widget-heading\" data-id=\"ae7d2c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 className=\"elementor-heading-title elementor-size-default\">Selecciona la vivienda<\/h2>\t\t\t\t<\/div>\n\t\t<div className=\"elementor-element elementor-element-f13cc17 e-grid e-con-full e-con e-child\" data-id=\"f13cc17\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;metform_multistep_settings_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;}}\">\n\t\t\t\t<div className=\"elementor-element elementor-element-f70a7b5 elementor-widget elementor-widget-mf-select\" data-id=\"f70a7b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-fase&quot;,&quot;mf_input_list&quot;:[{&quot;mf_input_option_text&quot;:&quot;Fase 1&quot;,&quot;mf_input_option_value&quot;:&quot;fase-1&quot;,&quot;_id&quot;:&quot;b6f1ca8&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Fase 2&quot;,&quot;mf_input_option_value&quot;:&quot;fase-2&quot;,&quot;_id&quot;:&quot;b5f965d&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Fase 3&quot;,&quot;mf_input_option_value&quot;:&quot;fase-3&quot;,&quot;_id&quot;:&quot;4e69989&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Fase 4&quot;,&quot;mf_input_option_value&quot;:&quot;fase-4&quot;,&quot;_id&quot;:&quot;981ee30&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Fase 6&quot;,&quot;mf_input_option_value&quot;:&quot;fase-6&quot;,&quot;_id&quot;:&quot;1ae7243&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Fase 7&quot;,&quot;mf_input_option_value&quot;:&quot;fase-7&quot;,&quot;_id&quot;:&quot;22454e1&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Fase 8&quot;,&quot;mf_input_option_value&quot;:&quot;fase-8&quot;,&quot;_id&quot;:&quot;ddcf527&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;}],&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-select.default\">\n\t\t\t\t\t\n\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-select-f70a7b5\">\n\t\t\t\t\t${ parent.decodeEntities(`Fase`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\n\t\t\t\t<\/label>\n            \n            <${props.Select}\n                className=${\"mf-input mf-input-select  \" + ( validation.errors['mf-fase'] ? 'mf-invalid' : '' )}\n                classNamePrefix=\"mf_select\"\n                name=\"mf-fase\"\n                placeholder=\"${ parent.decodeEntities(`Fase`) } \"\n                isSearchable=${false}\n                options=${[{\"label\":\"Fase 1\",\"value\":\"fase-1\",\"isDisabled\":false},{\"label\":\"Fase 2\",\"value\":\"fase-2\",\"isDisabled\":false},{\"label\":\"Fase 3\",\"value\":\"fase-3\",\"isDisabled\":false},{\"label\":\"Fase 4\",\"value\":\"fase-4\",\"isDisabled\":false},{\"label\":\"Fase 6\",\"value\":\"fase-6\",\"isDisabled\":false},{\"label\":\"Fase 7\",\"value\":\"fase-7\",\"isDisabled\":false},{\"label\":\"Fase 8\",\"value\":\"fase-8\",\"isDisabled\":false}]}\n                value=${parent.getValue(\"mf-fase\") ? [{\"label\":\"Fase 1\",\"value\":\"fase-1\",\"isDisabled\":false},{\"label\":\"Fase 2\",\"value\":\"fase-2\",\"isDisabled\":false},{\"label\":\"Fase 3\",\"value\":\"fase-3\",\"isDisabled\":false},{\"label\":\"Fase 4\",\"value\":\"fase-4\",\"isDisabled\":false},{\"label\":\"Fase 6\",\"value\":\"fase-6\",\"isDisabled\":false},{\"label\":\"Fase 7\",\"value\":\"fase-7\",\"isDisabled\":false},{\"label\":\"Fase 8\",\"value\":\"fase-8\",\"isDisabled\":false}].filter(item => item.value === parent.getValue(\"mf-fase\"))[0] : []}\n                onChange=${(e)=> parent.handleSelect(e, \"mf-fase\")}\n                ref=${() => {\n\t\t\t\t                    register({ name: \"mf-fase\" }, parent.activateValidation({\"message\":\"Este campo es obligatorio\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true}));\n                    if ( parent.getValue(\"mf-fase\") === '' && false ) {\n\t\t\t\t    parent.setValue( 'mf-fase', '', true );\n                        parent.handleChange({\n                            target: {\n                                name: 'mf-fase',\n                                value: ''\n                            }\n                        });\n                    }\n                }}\n                \/>\n\n            \t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"mf-fase\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-aa188f5 elementor-widget elementor-widget-mf-number\" data-id=\"aa188f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-bloque&quot;,&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-number.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-number-aa188f5\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Bloque`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"number\"\r\n\t\t\t\tstep=\"any\"\r\n\t\t\t\tclassName=\"mf-input \"\r\n\t\t\t\tid=\"mf-input-mobile-aa188f5\"\r\n\t\t\t\t\t\t\t\tname=\"mf-bloque\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Bloque`) } \"\r\n\t\t\t\t\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-bloque'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el => parent.activateValidation({\"message\":\"Este campo es obligatorio\",\"minLength\":1,\"maxLength\":12,\"type\":\"by_range\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-bloque\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-52f46e1 elementor-widget elementor-widget-mf-number\" data-id=\"52f46e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-escalera&quot;,&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-number.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-number-52f46e1\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Escalera`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"number\"\r\n\t\t\t\tstep=\"any\"\r\n\t\t\t\tclassName=\"mf-input \"\r\n\t\t\t\tid=\"mf-input-mobile-52f46e1\"\r\n\t\t\t\t\t\t\t\tname=\"mf-escalera\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Escalera`) } \"\r\n\t\t\t\t\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-escalera'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el => parent.activateValidation({\"message\":\"Este campo es obligatorio\",\"minLength\":1,\"maxLength\":34,\"type\":\"by_range\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-escalera\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-52fb9b5 elementor-widget elementor-widget-mf-select\" data-id=\"52fb9b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-planta&quot;,&quot;mf_input_list&quot;:[{&quot;mf_input_option_text&quot;:&quot;SM&quot;,&quot;mf_input_option_value&quot;:&quot;SM&quot;,&quot;_id&quot;:&quot;e9ef1d1&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;00&quot;,&quot;mf_input_option_value&quot;:&quot;00&quot;,&quot;_id&quot;:&quot;4a70f12&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;01&quot;,&quot;mf_input_option_value&quot;:&quot;01&quot;,&quot;_id&quot;:&quot;ce5804d&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;325bbe7&quot;,&quot;mf_input_option_text&quot;:&quot;02&quot;,&quot;mf_input_option_value&quot;:&quot;02&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;eba54c1&quot;,&quot;mf_input_option_text&quot;:&quot;03&quot;,&quot;mf_input_option_value&quot;:&quot;03&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;b5325c7&quot;,&quot;mf_input_option_text&quot;:&quot;AT&quot;,&quot;mf_input_option_value&quot;:&quot;AT&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;}],&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-select.default\">\n\t\t\t\t\t\n\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-select-52fb9b5\">\n\t\t\t\t\t${ parent.decodeEntities(`Planta`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\n\t\t\t\t<\/label>\n            \n            <${props.Select}\n                className=${\"mf-input mf-input-select  \" + ( validation.errors['mf-planta'] ? 'mf-invalid' : '' )}\n                classNamePrefix=\"mf_select\"\n                name=\"mf-planta\"\n                placeholder=\"${ parent.decodeEntities(`Planta`) } \"\n                isSearchable=${false}\n                options=${[{\"label\":\"SM\",\"value\":\"SM\",\"isDisabled\":false},{\"label\":\"00\",\"value\":\"00\",\"isDisabled\":false},{\"label\":\"01\",\"value\":\"01\",\"isDisabled\":false},{\"label\":\"02\",\"value\":\"02\",\"isDisabled\":false},{\"label\":\"03\",\"value\":\"03\",\"isDisabled\":false},{\"label\":\"AT\",\"value\":\"AT\",\"isDisabled\":false}]}\n                value=${parent.getValue(\"mf-planta\") ? [{\"label\":\"SM\",\"value\":\"SM\",\"isDisabled\":false},{\"label\":\"00\",\"value\":\"00\",\"isDisabled\":false},{\"label\":\"01\",\"value\":\"01\",\"isDisabled\":false},{\"label\":\"02\",\"value\":\"02\",\"isDisabled\":false},{\"label\":\"03\",\"value\":\"03\",\"isDisabled\":false},{\"label\":\"AT\",\"value\":\"AT\",\"isDisabled\":false}].filter(item => item.value === parent.getValue(\"mf-planta\"))[0] : []}\n                onChange=${(e)=> parent.handleSelect(e, \"mf-planta\")}\n                ref=${() => {\n\t\t\t\t                    register({ name: \"mf-planta\" }, parent.activateValidation({\"message\":\"Este campo es obligatorio\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true}));\n                    if ( parent.getValue(\"mf-planta\") === '' && false ) {\n\t\t\t\t    parent.setValue( 'mf-planta', '', true );\n                        parent.handleChange({\n                            target: {\n                                name: 'mf-planta',\n                                value: ''\n                            }\n                        });\n                    }\n                }}\n                \/>\n\n            \t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"mf-planta\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-6f2ba2d elementor-widget elementor-widget-mf-select\" data-id=\"6f2ba2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-puerta&quot;,&quot;mf_input_list&quot;:[{&quot;mf_input_option_text&quot;:&quot;A&quot;,&quot;mf_input_option_value&quot;:&quot;A&quot;,&quot;_id&quot;:&quot;e9ef1d1&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;B&quot;,&quot;mf_input_option_value&quot;:&quot;B&quot;,&quot;_id&quot;:&quot;4a70f12&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;C&quot;,&quot;mf_input_option_value&quot;:&quot;C&quot;,&quot;_id&quot;:&quot;ce5804d&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;0c1b230&quot;,&quot;mf_input_option_text&quot;:&quot;D&quot;,&quot;mf_input_option_value&quot;:&quot;D&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;817d960&quot;,&quot;mf_input_option_text&quot;:&quot;E&quot;,&quot;mf_input_option_value&quot;:&quot;E&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;acd4e56&quot;,&quot;mf_input_option_text&quot;:&quot;F&quot;,&quot;mf_input_option_value&quot;:&quot;F&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;}],&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-select.default\">\n\t\t\t\t\t\n\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-select-6f2ba2d\">\n\t\t\t\t\t${ parent.decodeEntities(`Puerta`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\n\t\t\t\t<\/label>\n            \n            <${props.Select}\n                className=${\"mf-input mf-input-select  \" + ( validation.errors['mf-puerta'] ? 'mf-invalid' : '' )}\n                classNamePrefix=\"mf_select\"\n                name=\"mf-puerta\"\n                placeholder=\"${ parent.decodeEntities(`Puerta`) } \"\n                isSearchable=${false}\n                options=${[{\"label\":\"A\",\"value\":\"A\",\"isDisabled\":false},{\"label\":\"B\",\"value\":\"B\",\"isDisabled\":false},{\"label\":\"C\",\"value\":\"C\",\"isDisabled\":false},{\"label\":\"D\",\"value\":\"D\",\"isDisabled\":false},{\"label\":\"E\",\"value\":\"E\",\"isDisabled\":false},{\"label\":\"F\",\"value\":\"F\",\"isDisabled\":false}]}\n                value=${parent.getValue(\"mf-puerta\") ? [{\"label\":\"A\",\"value\":\"A\",\"isDisabled\":false},{\"label\":\"B\",\"value\":\"B\",\"isDisabled\":false},{\"label\":\"C\",\"value\":\"C\",\"isDisabled\":false},{\"label\":\"D\",\"value\":\"D\",\"isDisabled\":false},{\"label\":\"E\",\"value\":\"E\",\"isDisabled\":false},{\"label\":\"F\",\"value\":\"F\",\"isDisabled\":false}].filter(item => item.value === parent.getValue(\"mf-puerta\"))[0] : []}\n                onChange=${(e)=> parent.handleSelect(e, \"mf-puerta\")}\n                ref=${() => {\n\t\t\t\t                    register({ name: \"mf-puerta\" }, parent.activateValidation({\"message\":\"Este campo es obligatorio\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true}));\n                    if ( parent.getValue(\"mf-puerta\") === '' && false ) {\n\t\t\t\t    parent.setValue( 'mf-puerta', '', true );\n                        parent.handleChange({\n                            target: {\n                                name: 'mf-puerta',\n                                value: ''\n                            }\n                        });\n                    }\n                }}\n                \/>\n\n            \t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"mf-puerta\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-60c41cb elementor-widget__width-inherit elementor-widget elementor-widget-mf-textarea\" data-id=\"60c41cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-comentarios&quot;,&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-textarea.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-area-60c41cb\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Comentarios`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\"><\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<textarea className=\"mf-input mf-textarea \" id=\"mf-input-text-area-60c41cb\"\r\n\t\t\t\tname=\"mf-comentarios\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Comentarios`) } \"\r\n\t\t\t\tcols=\"30\" rows=\"10\"\r\n\t\t\t\t\t\t\t\t\tonInput=${ parent.handleChange }\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-comentarios'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${ el => parent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":false,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\t><\/textarea>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-comentarios\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-61c563e elementor-widget__width-inherit elementor-widget elementor-widget-mf-gdpr-consent\" data-id=\"61c563e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-veracidad&quot;,&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-gdpr-consent.default\">\n\t\t\t\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\n\t\t\t<div className=\"mf-checkbox multi-option-input-type\" id=\"mf-input-gdpr-61c563e\">\n\t\t\t\t<div className=\"mf-checkbox-option\">\n\t\t\t\t\t<label>\n\t\t\t\t\t\t\t\t\t\t\t\t<input\n\t\t\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\t\t\tclassName=\"mf-input mf-checkbox-input \"\n\t\t\t\t\t\t\tname=\"mf-veracidad\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tonInput=${ parent.handleOptin }\n\t\t\t\t\t\t\t\taria-invalid=${validation.errors['mf-veracidad'] ? 'true' : 'false'}\n\t\t\t\t\t\t\t\tref=${ el => parent.activateValidation({\"message\":\"Este campo es obligatorio\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el) }\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\tDeclaro que los datos personales facilitados son veraces y exactos, y autorizo a que puedan ser verificados o contrastados con la administraci\u00f3n de fincas correspondiente, \u00fanicamente con el fin de comprobar mi identidad y relaci\u00f3n con la comunidad.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"mf-veracidad\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-f2ecb2a elementor-widget elementor-widget-mf-listing-optin\" data-id=\"f2ecb2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;optin_marketing&quot;,&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-listing-optin.default\">\n\t\t\t\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\n\t\t\t<div className=\"mf-checkbox multi-option-input-type\" id=\"mf-input-optin-f2ecb2a\">\n\t\t\t\t<div className=\"mf-checkbox-option\">\n\t\t\t\t\t<label>\n\t\t\t\t\t\t\t\t\t\t\t\t<input\n\t\t\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\t\t\tclassName=\"mf-input mf-checkbox-input \"\n\t\t\t\t\t\t\tname=\"optin_marketing\" \n\t\t\t\t\t\t\tvalue=\"1\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tonInput=${ parent.handleOptin }\n\t\t\t\t\t\t\t\taria-invalid=${validation.errors['optin_marketing'] ? 'true' : 'false'}\n\t\t\t\t\t\t\t\tref=${el => parent.activateValidation({\"message\":\"This field is required.\",\"required\":false}, el)}\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\tAutorizo el env\u00edo de informaci\u00f3n y comunicaciones relacionadas con eventos, reuniones y actividades organizadas por BilbilHouse, de acuerdo con la pol\u00edtica de privacidad.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"optin_marketing\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-5c7a685 elementor-widget__width-inherit elementor-widget elementor-widget-mf-gdpr-consent\" data-id=\"5c7a685\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-gdpr-consent&quot;,&quot;mf_input_get_params_enable&quot;:&quot;no&quot;}\" data-widget_type=\"mf-gdpr-consent.default\">\n\t\t\t\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\n\t\t\t<div className=\"mf-checkbox multi-option-input-type\" id=\"mf-input-gdpr-5c7a685\">\n\t\t\t\t<div className=\"mf-checkbox-option\">\n\t\t\t\t\t<label>\n\t\t\t\t\t\t\t\t\t\t\t\t<input\n\t\t\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\t\t\tclassName=\"mf-input mf-checkbox-input \"\n\t\t\t\t\t\t\tname=\"mf-gdpr-consent\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tonInput=${ parent.handleOptin }\n\t\t\t\t\t\t\t\taria-invalid=${validation.errors['mf-gdpr-consent'] ? 'true' : 'false'}\n\t\t\t\t\t\t\t\tref=${ el => parent.activateValidation({\"message\":\"Este campo es obligatorio\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el) }\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\tHe le\u00eddo y acepto la <a href=\"\/aviso-legal\/\">pol\u00edtica de privacidad<\/a>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"mf-gdpr-consent\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-8223660 elementor-widget elementor-widget-text-editor\" data-id=\"8223660\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>En caso de encontrar incongruencias con esta vivienda, m\u00e1s personas de la cuenta, o datos que no corresponden con lo que el vecino nos indica en oficina, procederemos a contactar con la administraci\u00f3n pertinente para cerciorarnos de la veracidad de estos datos.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-83f5574 elementor-widget__width-initial elementor-widget elementor-widget-mf-signature\" data-id=\"83f5574\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-firma&quot;}\" data-widget_type=\"mf-signature.default\">\n\t\t\t\t\t\n\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\t\t\t\t<label className=\"mf-signature-label mf-input-label\">\n\t\t\t\t\t${ parent.decodeEntities(`Firma`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\n\t\t\t\t<\/label>\n\t\t\t\n\t\t\t<div className=\"mf-signature\" id=\"mf-input-signature-83f5574\" aria-invalid=${validation.errors[ 'mf-firma' ] ? 'true' : 'false'}>\n\t\t\t\t<${props.SignaturePad}\n\t\t\t\t\tclearButton=\"true\"\n\t\t\t\t\tpenColor=\"\"\n\t\t\t\t\tname=\"mf-firma\"\n\t\t\t\t\tonEnd=${function () { parent.handleSignature(this) }}\n\t\t\t\t\t\/>\n\t\t\t\t\n\t\t\t\t<input\n\t\t\t\t\ttype=\"hidden\"\n\t\t\t\t\tname=\"mf-firma\"\n\t\t\t\t\tclassName=\"mf-input mf-signature-hidden\"\n\t\t\t\t\tvalue=${ parent.getValue( 'mf-firma' ) }\n\t\t\t\t\tref=${ (el) => parent.activateValidation({\"message\":\"Este campo es obligatorio\",\"required\":true}, el) }\n\t\t\t\t\t\/>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"mf-firma\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-e0c88fb elementor-widget elementor-widget-mf-recaptcha\" data-id=\"e0c88fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mf-recaptcha.default\">\n\t\t\t\t\t\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div id=\"recaptcha_site_key_v3\" data-sitekey=\"6Lfpz-MrAAAAABXJicYNWBjhZZjikw-UBMIzzFIf\"  className=\"recaptcha_site_key_v3 \">\n\t\t\t\t\t\t<input type=\"hidden\" className=\"g-recaptcha-response-v3\" name=\"g-recaptcha-response-v3\" \/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t<div className=\"elementor-element elementor-element-ec02c5f e-con-full e-flex e-con e-child\" data-id=\"ec02c5f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;metform_multistep_settings_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;}}\">\n\t\t\t\t<div className=\"elementor-element elementor-element-92b7856 elementor-widget__width-auto e-transform mf-btn--center elementor-widget elementor-widget-mf-prev-step\" data-id=\"92b7856\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-10,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"mf-prev-step.default\">\n\t\t\t\t\t\t\t<div className=\"mf-btn-wraper \">\n\t\t\t\t\t\t\t<button type=\"button\"\n\t\t\t\t\t\tclassName=\"metform-btn metfrom-prev-step \"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-direction=\"prev\"\n\t\t\t\t\t\t\t\t\t\t\t\tonClick=${ parent.handleMultiStepBtns }\n\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t<i aria-hidden=\"true\" className=\" ti-arrow-left\"><\/i>\t\t\t\t\t${ parent.decodeEntities(`Paso previo`) } \t\t\t\t<\/button>\n\t\t\t\t        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-7f6c382 elementor-widget__width-auto e-transform mf-btn--center elementor-widget elementor-widget-mf-button\" data-id=\"7f6c382\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-10,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"mf-button.default\">\n\t\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"\" className=\"\" value=\"\" ref=${parent.setDefault} \/>\r\n\t\t\t\t\t\t<div className=\"mf-btn-wraper \" data-mf-form-conditional-logic-requirement=\"\">\r\n\t\t\t\t\t\t\t<button type=\"submit\" className=\"metform-btn metform-submit-btn \" id=\"\">\r\n\t\t\t\t\t<span>${ parent.decodeEntities(`Enviar`) } <\/span>\r\n\t\t\t\t<\/button>\r\n\t\t\t        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t`}\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'bottom' ? props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' : message_position === 'bottom' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\t\t\t\t\r\n\t\t\t\t<\/form>\r\n\t\t\t`\r\n\t\t<\/script>\r\n\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2383","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alta de vecinos - BilBil House<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alta de vecinos - BilBil House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bilbilhouse.com\/en\/alta-de-vecinos\/\" \/>\n<meta property=\"og:site_name\" content=\"BilBil House\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-10T13:52:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bilbilhouse.com\\\/alta-de-vecinos\\\/\",\"url\":\"https:\\\/\\\/bilbilhouse.com\\\/alta-de-vecinos\\\/\",\"name\":\"Alta de vecinos - BilBil House\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bilbilhouse.com\\\/#website\"},\"datePublished\":\"2025-10-31T09:21:12+00:00\",\"dateModified\":\"2025-11-10T13:52:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bilbilhouse.com\\\/alta-de-vecinos\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bilbilhouse.com\\\/alta-de-vecinos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bilbilhouse.com\\\/alta-de-vecinos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bilbilhouse.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alta de vecinos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bilbilhouse.com\\\/#website\",\"url\":\"https:\\\/\\\/bilbilhouse.com\\\/\",\"name\":\"BilBil House\",\"description\":\"Deporte, Gastronom\u00eda y Eventos en Benalm\u00e1dena\",\"publisher\":{\"@id\":\"https:\\\/\\\/bilbilhouse.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bilbilhouse.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bilbilhouse.com\\\/#organization\",\"name\":\"BilBil House\",\"url\":\"https:\\\/\\\/bilbilhouse.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/bilbilhouse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bilbilhouse.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-bil-bil-house-logo-azul.png\",\"contentUrl\":\"https:\\\/\\\/bilbilhouse.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-bil-bil-house-logo-azul.png\",\"width\":911,\"height\":1175,\"caption\":\"BilBil House\"},\"image\":{\"@id\":\"https:\\\/\\\/bilbilhouse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alta de vecinos - BilBil House","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"en_GB","og_type":"article","og_title":"Alta de vecinos - BilBil House","og_url":"https:\/\/bilbilhouse.com\/en\/alta-de-vecinos\/","og_site_name":"BilBil House","article_modified_time":"2025-11-10T13:52:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bilbilhouse.com\/alta-de-vecinos\/","url":"https:\/\/bilbilhouse.com\/alta-de-vecinos\/","name":"Alta de vecinos - BilBil House","isPartOf":{"@id":"https:\/\/bilbilhouse.com\/#website"},"datePublished":"2025-10-31T09:21:12+00:00","dateModified":"2025-11-10T13:52:53+00:00","breadcrumb":{"@id":"https:\/\/bilbilhouse.com\/alta-de-vecinos\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bilbilhouse.com\/alta-de-vecinos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bilbilhouse.com\/alta-de-vecinos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bilbilhouse.com\/"},{"@type":"ListItem","position":2,"name":"Alta de vecinos"}]},{"@type":"WebSite","@id":"https:\/\/bilbilhouse.com\/#website","url":"https:\/\/bilbilhouse.com\/","name":"BilBil House","description":"Sports, Gastronomy and Events in Benalm\u00e1dena","publisher":{"@id":"https:\/\/bilbilhouse.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bilbilhouse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/bilbilhouse.com\/#organization","name":"BilBil House","url":"https:\/\/bilbilhouse.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/bilbilhouse.com\/#\/schema\/logo\/image\/","url":"https:\/\/bilbilhouse.com\/wp-content\/uploads\/2025\/09\/cropped-bil-bil-house-logo-azul.png","contentUrl":"https:\/\/bilbilhouse.com\/wp-content\/uploads\/2025\/09\/cropped-bil-bil-house-logo-azul.png","width":911,"height":1175,"caption":"BilBil House"},"image":{"@id":"https:\/\/bilbilhouse.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bilbilhouse.com\/en\/wp-json\/wp\/v2\/pages\/2383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bilbilhouse.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bilbilhouse.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bilbilhouse.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bilbilhouse.com\/en\/wp-json\/wp\/v2\/comments?post=2383"}],"version-history":[{"count":3,"href":"https:\/\/bilbilhouse.com\/en\/wp-json\/wp\/v2\/pages\/2383\/revisions"}],"predecessor-version":[{"id":3881,"href":"https:\/\/bilbilhouse.com\/en\/wp-json\/wp\/v2\/pages\/2383\/revisions\/3881"}],"wp:attachment":[{"href":"https:\/\/bilbilhouse.com\/en\/wp-json\/wp\/v2\/media?parent=2383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}